{"id":36812,"date":"2025-12-12T17:32:03","date_gmt":"2025-12-12T17:32:03","guid":{"rendered":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/?post_type=product&#038;p=36812"},"modified":"2025-12-12T17:32:53","modified_gmt":"2025-12-12T17:32:53","slug":"empresas-con-mas-150-empleados-a-nivel-nacional-mexico","status":"publish","type":"product","link":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/product\/empresas-con-mas-150-empleados-a-nivel-nacional-mexico\/","title":{"rendered":"Empresas con m\u00e1s 150 empleados a Nivel Nacional (M\u00e9xico)."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n<div class=\"row\">\n<div class=\"col-sm\"><strong>C\u00f3digo:<\/strong> <strong class=\"text-danger\"> MIRO-C0<\/strong><\/div>\n<div class=\"col-sm\"><strong>N\u00famero de registros: <\/strong>300<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm \"><strong>Folio: <\/strong><span class=\"text-danger\">03WGMT0523-017<\/span><\/div>\n<\/div>\n<p><strong>Segmentaci\u00f3n:<\/strong><\/p>\n<div class=\"row\">\n<div class=\"col-sm \">Empresas con m\u00e1s 150 empleados usen SAP a Nivel Nacional.<\/div>\n<\/div>\n<p><strong>Campos Contenidos:<\/strong><\/p>\n<div class=\"row\">\n<div class=\"col-sm \">Empresa (Raz\u00f3n Social o Comercial) \/ Sector y\/o Sub Sector \/ Domicilio \/ Ciudad \/ Estado \/ Nombre de la Persona \/ Puesto : Director de TI, Gerente de TI, Encargado de TI, Director de Compras, Gerente de Compras, Encargado de Compras, Director de Finanzas, Gerente de Finanzas o Encargado de Finanzas \/ Tel\u00e9fono fijo \/ Correo \/ Sitio web*opcional.<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm\"><strong>Garant\u00eda: <\/strong>80%-85% <strong>Precio Original: <\/strong><del>USD 182<\/del> <strong>Descuento Especial: <\/strong><strong class=\"text-danger\">20%<\/strong><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col text-center\"><strong>Total a Pagar: <\/strong><strong class=\"text-danger\">USD 146<\/strong><\/div>\n<\/div>\n","protected":false},"featured_media":31013,"template":"","meta":{"_bst_post_transparent":"","_bst_post_title":"","_bst_post_layout":"","_bst_post_sidebar_id":"","_bst_post_content_style":"","_bst_post_vertical_padding":"","_bst_post_feature":"","_bst_post_feature_position":"","_bst_post_header":false,"_bst_post_footer":false},"product_brand":[],"product_cat":[1379,1060],"product_tag":[1062,1063,1064,1067,1068,1152,1319,1274,1442,1385,1071,1072,1074,1075,1076,1077,1079,1155,1386,1243,1176,1177,1081,1083,1084,1085,1086,1335,1160,1088,1089,1224,1099,1101,1246,1102,1104,1105,1107,1110,1118,1170,1125,1126,1127,1309,1128,1129,1390,1130,1133,1135,1136,1509,1422,1220,1137,1138,1140,1142,1144,1145,1172,1175,1146,1273,1549,1149],"product_brands":[],"class_list":{"0":"post-36812","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-con-mas-de-100-empleados","7":"product_cat-empresas-en-mexico","8":"product_tag-b2c-email-database","9":"product_tag-base-de-datos-campana-de-email-marketing","10":"product_tag-base-de-datos-campanas-de-email-marketing","11":"product_tag-base-de-datos-correo-masivo","12":"product_tag-base-de-datos-correo-masivos","13":"product_tag-base-de-datos-de-directivos","14":"product_tag-base-de-datos-de-empresas-con-mas-de-100-empleados","15":"product_tag-base-de-datos-de-empresas-en-mexico","16":"product_tag-base-de-datos-de-empresas-mexicanas","17":"product_tag-base-de-datos-de-mexico","18":"product_tag-base-de-datos-direct-e-mail-marketing","19":"product_tag-base-de-datos-director","20":"product_tag-base-de-datos-email-marketer","21":"product_tag-base-de-datos-email-marketing","22":"product_tag-base-de-datos-email-masivos","23":"product_tag-base-de-datos-email-publicidad","24":"product_tag-base-de-datos-emailing","25":"product_tag-base-de-datos-empresas","26":"product_tag-base-de-datos-empresas-en-mexico","27":"product_tag-base-de-datos-empresas-medianas","28":"product_tag-base-de-datos-encargados","29":"product_tag-base-de-datos-encargados-de-compras","30":"product_tag-base-de-datos-enviar-email-masivo","31":"product_tag-base-de-datos-envio-masivo-correo","32":"product_tag-base-de-datos-envio-masivo-correos","33":"product_tag-base-de-datos-envio-masivo-de-emails","34":"product_tag-base-de-datos-envios-de-correo-masivos","35":"product_tag-base-de-datos-finanzas","36":"product_tag-base-de-datos-gerente","37":"product_tag-base-de-datos-marketing","38":"product_tag-base-de-datos-marketing-por-e-mail","39":"product_tag-base-de-datos-nivel-nacional","40":"product_tag-bases-de-datos-de-emails","41":"product_tag-bases-de-datos-de-telefonos","42":"product_tag-bases-de-datos-director-de-ti","43":"product_tag-bases-de-datos-email","44":"product_tag-bases-de-datos-emailing","45":"product_tag-bases-de-datos-numeros-de-telefonos","46":"product_tag-bases-de-datos-telefonos-fijos","47":"product_tag-business-directory","48":"product_tag-buy-email-list-database","49":"product_tag-database","50":"product_tag-director","51":"product_tag-directorio-emailing","52":"product_tag-directorio-empresarial","53":"product_tag-directorio-empresarial-mexico","54":"product_tag-directorio-empresariales","55":"product_tag-directorio-empresas","56":"product_tag-directorio-mexico","57":"product_tag-directorios-de-empresas","58":"product_tag-email-address-list","59":"product_tag-email-lists","60":"product_tag-email-marketing-list","61":"product_tag-encargado","62":"product_tag-gerente","63":"product_tag-gerentes","64":"product_tag-list-of-email-addresses","65":"product_tag-lista-de-correos","66":"product_tag-mail-marketing","67":"product_tag-mailing-list","68":"product_tag-marketing-correo-electronico","69":"product_tag-marketing-lists","70":"product_tag-phone-database","71":"product_tag-phone-number-list","72":"product_tag-publicidad-por-base-de-datos-correo-electronico","73":"product_tag-publicidad-por-base-de-datos-correo-electronico-bases-de-datos-de-telefonos","74":"product_tag-sap","75":"product_tag-telefono","77":"first","78":"instock","79":"sale","80":"virtual","81":"purchasable","82":"product-type-simple","83":"entry","84":"content-bg","85":"loop-entry"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product\/36812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product\/36812\/revisions"}],"predecessor-version":[{"id":36861,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product\/36812\/revisions\/36861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/media\/31013"}],"wp:attachment":[{"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/media?parent=36812"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product_brand?post=36812"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product_cat?post=36812"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product_tag?post=36812"},{"taxonomy":"product_brands","embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product_brands?post=36812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}