{"id":35183,"date":"2025-12-12T17:01:32","date_gmt":"2025-12-12T17:01:32","guid":{"rendered":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/?post_type=product&#038;p=35183"},"modified":"2025-12-12T17:02:13","modified_gmt":"2025-12-12T17:02:13","slug":"empresas-manufactureras-del-sector-alimenticio-farmaceutico-automotriz-y-siderurgico-a-nivel-nacional","status":"publish","type":"product","link":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/product\/empresas-manufactureras-del-sector-alimenticio-farmaceutico-automotriz-y-siderurgico-a-nivel-nacional\/","title":{"rendered":"Empresas manufactureras, del sector alimenticio, farmac\u00e9utico, automotriz y sider\u00fargico a Nivel Nacional."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n<div class=\"row\">\n<div class=\"col-sm\"><strong>C\u00f3digo:<\/strong> <strong class=\"text-danger\">IVHV-K05<\/strong><\/div>\n<div class=\"col-sm\"><strong>N\u00famero de registros: <\/strong>250<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm \"><strong>Folio: <\/strong><span class=\"text-danger\">HI0220B047<\/span><\/div>\n<\/div>\n<p><strong>Segmentaci\u00f3n:<\/strong><\/p>\n<div class=\"row\">\n<div class=\"col-sm \"><span class=\"text-justify\">Empresas manufactureras, del sector alimenticio, farmac\u00e9utico, automotriz y sider\u00fargico a Nivel Nacional.<\/span><\/div>\n<\/div>\n<p><strong>Campos Contenidos:<\/strong><\/p>\n<div class=\"row\">\n<div class=\"col-sm \"><span class=\"text-justify\">Empresa \/ Giro \/ Direcci\u00f3n \/ Ciudad \/ Estado \/ Contacto \/ Puesto: Gerente o director de log\u00edstica\/ Tel\u00e9fono \/ Email \/ P\u00e1gina web*opcional.<\/span><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm\">\n<p><strong>Garant\u00eda: <\/strong>80%-85%<\/p>\n<p><strong>Precio Original: <\/strong><del>$131 USD<\/del><\/p>\n<p><strong>Descuento Especial: <\/strong><strong class=\"text-danger\">20%<\/strong><\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col text-center\"><strong>Total a Pagar: <\/strong><strong class=\"text-danger\">$105 USD<\/strong><\/div>\n<\/div>\n","protected":false},"featured_media":31017,"template":"","meta":{"_bst_post_transparent":"","_bst_post_title":"","_bst_post_layout":"","_bst_post_sidebar_id":"","_bst_post_content_style":"","_bst_post_vertical_padding":"","_bst_post_feature":"","_bst_post_feature_position":"","_bst_post_header":false,"_bst_post_footer":false},"product_brand":[],"product_cat":[1060,1259],"product_tag":[1062,1260,1363,1063,1064,1067,1068,1071,1072,1074,1075,1076,1077,1078,1079,1080,1081,1082,1083,1084,1085,1086,1160,1261,1088,1090,1224,1093,1097,1098,1099,1101,1102,1103,1104,1226,1105,1106,1107,1229,1110,1111,1112,1114,1115,1116,1117,1118,1119,1120,1121,1122,1123,1124,1170,1125,1126,1127,1128,1129,1130,1131,1132,1133,1134,1135,1136,1219,1137,1138,1139,1140,1141,1142,1144,1145,1230,1206,1172,1173,1174,1175,1146,1149],"product_brands":[],"class_list":{"0":"post-35183","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-empresas-en-mexico","7":"product_cat-manufactureras","8":"product_tag-b2c-email-database","9":"product_tag-base-de-datos-alimentos","10":"product_tag-base-de-datos-automotriz","11":"product_tag-base-de-datos-campana-de-email-marketing","12":"product_tag-base-de-datos-campanas-de-email-marketing","13":"product_tag-base-de-datos-correo-masivo","14":"product_tag-base-de-datos-correo-masivos","15":"product_tag-base-de-datos-direct-e-mail-marketing","16":"product_tag-base-de-datos-director","17":"product_tag-base-de-datos-email-marketer","18":"product_tag-base-de-datos-email-marketing","19":"product_tag-base-de-datos-email-masivos","20":"product_tag-base-de-datos-email-publicidad","21":"product_tag-base-de-datos-email-publicitario","22":"product_tag-base-de-datos-emailing","23":"product_tag-base-de-datos-empresas-de-email-marketing","24":"product_tag-base-de-datos-enviar-email-masivo","25":"product_tag-base-de-datos-envio-de-email-masivo","26":"product_tag-base-de-datos-envio-masivo-correo","27":"product_tag-base-de-datos-envio-masivo-correos","28":"product_tag-base-de-datos-envio-masivo-de-emails","29":"product_tag-base-de-datos-envios-de-correo-masivos","30":"product_tag-base-de-datos-gerente","31":"product_tag-base-de-datos-manufacturera","32":"product_tag-base-de-datos-marketing","33":"product_tag-base-de-datos-marketing-por-email","34":"product_tag-base-de-datos-nivel-nacional","35":"product_tag-base-de-datos-publicidad-por-email","36":"product_tag-bases-de-datos-correos","37":"product_tag-bases-de-datos-correos-electronicos","38":"product_tag-bases-de-datos-de-emails","39":"product_tag-bases-de-datos-de-telefonos","40":"product_tag-bases-de-datos-email","41":"product_tag-bases-de-datos-email-empresas","42":"product_tag-bases-de-datos-emailing","43":"product_tag-bases-de-datos-emails","44":"product_tag-bases-de-datos-numeros-de-telefonos","45":"product_tag-bases-de-datos-telefono","46":"product_tag-bases-de-datos-telefonos-fijos","47":"product_tag-big-corporates-database","48":"product_tag-business-directory","49":"product_tag-business-email-database","50":"product_tag-business-email-list","51":"product_tag-business-mailing-database","52":"product_tag-business-mailing-lists","53":"product_tag-buy-email-database","54":"product_tag-buy-email-list","55":"product_tag-buy-email-list-database","56":"product_tag-company-database","57":"product_tag-correo-de-empresas","58":"product_tag-correos-de-empresas","59":"product_tag-correos-electronicos-de-empresas","60":"product_tag-correos-electronicos-empresas","61":"product_tag-correos-empresariales","62":"product_tag-database","63":"product_tag-director","64":"product_tag-directorio-emailing","65":"product_tag-directorio-empresarial","66":"product_tag-directorio-empresariales","67":"product_tag-directorio-empresas","68":"product_tag-directorios-de-empresas","69":"product_tag-directorios-empresas","70":"product_tag-e-mail-database","71":"product_tag-email-address-list","72":"product_tag-email-database","73":"product_tag-email-lists","74":"product_tag-email-marketing-list","75":"product_tag-engineering-services-databases","76":"product_tag-list-of-email-addresses","77":"product_tag-lista-de-correos","78":"product_tag-lista-de-correos-electronicos","79":"product_tag-mail-marketing","80":"product_tag-mailing-database","81":"product_tag-mailing-list","82":"product_tag-marketing-correo-electronico","83":"product_tag-marketing-lists","84":"product_tag-national-database","85":"product_tag-phone","86":"product_tag-phone-database","87":"product_tag-phone-lists","88":"product_tag-phone-number","89":"product_tag-phone-number-list","90":"product_tag-publicidad-por-base-de-datos-correo-electronico","91":"product_tag-telefono","93":"first","94":"instock","95":"sale","96":"virtual","97":"purchasable","98":"product-type-simple","99":"entry","100":"content-bg","101":"loop-entry"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product\/35183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product\/35183\/revisions"}],"predecessor-version":[{"id":35227,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product\/35183\/revisions\/35227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/media\/31017"}],"wp:attachment":[{"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/media?parent=35183"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product_brand?post=35183"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product_cat?post=35183"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product_tag?post=35183"},{"taxonomy":"product_brands","embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product_brands?post=35183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}