{"id":34624,"date":"2025-12-12T16:54:03","date_gmt":"2025-12-12T16:54:03","guid":{"rendered":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/?post_type=product&#038;p=34624"},"modified":"2025-12-12T16:54:40","modified_gmt":"2025-12-12T16:54:40","slug":"personas-fisicas-edad-de-25-hasta-74-anos-11-meses-ingresos-minimos-comprobables-de-50000-00-mxn-a-nivel-nacional-2","status":"publish","type":"product","link":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/product\/personas-fisicas-edad-de-25-hasta-74-anos-11-meses-ingresos-minimos-comprobables-de-50000-00-mxn-a-nivel-nacional-2\/","title":{"rendered":"Personas f\u00edsicas Edad de 25 hasta 74 a\u00f1os 11 meses. Ingresos m\u00ednimos comprobables de $50,000.00 MXN  a Nivel Nacional."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n<div class=\"row\">\n<div class=\"col-sm\"><strong>C\u00f3digo:<\/strong> <strong class=\"text-danger\">NBIF-D1-9<\/strong><\/div>\n<div class=\"col-sm\"><strong>N\u00famero de registros: <\/strong>3400<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm \"><strong>Folio: <\/strong><span class=\"text-danger\">GD0215B100<\/span><\/div>\n<\/div>\n<p><strong>Segmentaci\u00f3n:<\/strong><\/p>\n<div class=\"row\">\n<div class=\"col-sm \">Personas f\u00edsicas Edad de 25 hasta 74 a\u00f1os 11 meses. Ingresos m\u00ednimos comprobables de $50,000.00 MXN a Nivel Nacional.<\/div>\n<\/div>\n<p><strong>Campos Contenidos:<\/strong><\/p>\n<div class=\"row\">\n<div class=\"col-sm \">Nombre \/ Ciudad \/ Estado \/ Celular \/ Tel\u00e9fono fijo *opcional\/ Email.<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm\"><strong>Garant\u00eda:\u00a0<\/strong>75%-85%\u00a0<strong>Precio Original:<del>\u00a0<\/del><\/strong><del>$2463 USD<\/del>\u00a0<strong>Descuento Especial:\u00a0<\/strong><strong class=\"text-danger\">25%<\/strong><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col text-center\"><strong>Total a Pagar:\u00a0<\/strong><strong class=\"text-danger\">$1847 USD<\/strong><\/div>\n<\/div>\n","protected":false},"featured_media":31021,"template":"","meta":{"_bst_post_transparent":"","_bst_post_title":"","_bst_post_layout":"","_bst_post_sidebar_id":"","_bst_post_content_style":"","_bst_post_vertical_padding":"","_bst_post_feature":"","_bst_post_feature_position":"","_bst_post_header":false,"_bst_post_footer":false},"product_brand":[],"product_cat":[1266,1180],"product_tag":[1062,1063,1064,1404,1263,1067,1068,1294,1186,1405,1071,1073,1074,1075,1076,1077,1078,1079,1081,1082,1157,1083,1084,1085,1158,1086,1159,1088,1089,1090,1224,1295,1092,1189,1093,1406,1097,1098,1099,1100,1101,1102,1104,1105,1106,1107,1190,1109,1116,1117,1118,1191,1192,1194,1195,1196,1197,1198,1199,1200,1201,1202,1265,1203,1204,1170,1132,1133,1134,1135,1136,1137,1138,1139,1296,1140,1142,1143,1144,1145,1407,1297,1298,1299,1300,1301,1302,1303,1206,1172,1173,1174,1175,1146,1148,1149],"product_brands":[],"class_list":{"0":"post-34624","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-consumidores","7":"product_cat-personas-en-mexico","8":"product_tag-b2c-email-database","9":"product_tag-base-de-datos-campana-de-email-marketing","10":"product_tag-base-de-datos-campanas-de-email-marketing","11":"product_tag-base-de-datos-celulares","12":"product_tag-base-de-datos-consumidores","13":"product_tag-base-de-datos-correo-masivo","14":"product_tag-base-de-datos-correo-masivos","15":"product_tag-base-de-datos-de-numeros-celulares","16":"product_tag-base-de-datos-de-personas-fisicas","17":"product_tag-base-de-datos-de-telefonos-moviles","18":"product_tag-base-de-datos-direct-e-mail-marketing","19":"product_tag-base-de-datos-e-mail-marketing","20":"product_tag-base-de-datos-email-marketer","21":"product_tag-base-de-datos-email-marketing","22":"product_tag-base-de-datos-email-masivos","23":"product_tag-base-de-datos-email-publicidad","24":"product_tag-base-de-datos-email-publicitario","25":"product_tag-base-de-datos-emailing","26":"product_tag-base-de-datos-enviar-email-masivo","27":"product_tag-base-de-datos-envio-de-email-masivo","28":"product_tag-base-de-datos-envio-masivo","29":"product_tag-base-de-datos-envio-masivo-correo","30":"product_tag-base-de-datos-envio-masivo-correos","31":"product_tag-base-de-datos-envio-masivo-de-emails","32":"product_tag-base-de-datos-envio-masivos","33":"product_tag-base-de-datos-envios-de-correo-masivos","34":"product_tag-base-de-datos-envios-masivos","35":"product_tag-base-de-datos-marketing","36":"product_tag-base-de-datos-marketing-por-e-mail","37":"product_tag-base-de-datos-marketing-por-email","38":"product_tag-base-de-datos-nivel-nacional","39":"product_tag-base-de-datos-numeros-de-telefonos-celulares","40":"product_tag-base-de-datos-para-marketing","41":"product_tag-base-de-datos-personas-de-email-marketing","42":"product_tag-base-de-datos-publicidad-por-email","43":"product_tag-base-de-datos-telefonos-moviles","44":"product_tag-bases-de-datos-correos","45":"product_tag-bases-de-datos-correos-electronicos","46":"product_tag-bases-de-datos-de-emails","47":"product_tag-bases-de-datos-de-marketing","48":"product_tag-bases-de-datos-de-telefonos","49":"product_tag-bases-de-datos-email","50":"product_tag-bases-de-datos-emailing","51":"product_tag-bases-de-datos-numeros-de-telefonos","52":"product_tag-bases-de-datos-telefono","53":"product_tag-bases-de-datos-telefonos-fijos","54":"product_tag-big-consumer-database","55":"product_tag-business-contact-lists","56":"product_tag-buy-email-database","57":"product_tag-buy-email-list","58":"product_tag-buy-email-list-database","59":"product_tag-consumer-contact-lists","60":"product_tag-consumer-database","61":"product_tag-consumer-email-database","62":"product_tag-consumer-email-list","63":"product_tag-consumer-email-lists","64":"product_tag-consumer-list","65":"product_tag-consumer-mailing-database","66":"product_tag-consumer-mailing-list","67":"product_tag-consumer-mailing-lists","68":"product_tag-consumer-phone-list","69":"product_tag-correo-de-personas","70":"product_tag-correos-consumidores","71":"product_tag-correos-electronicos-de-personas","72":"product_tag-correos-electronicos-personas","73":"product_tag-database","74":"product_tag-e-mail-database","75":"product_tag-email-address-list","76":"product_tag-email-database","77":"product_tag-email-lists","78":"product_tag-email-marketing-list","79":"product_tag-list-of-email-addresses","80":"product_tag-lista-de-correos","81":"product_tag-lista-de-correos-electronicos","82":"product_tag-lista-de-numeros-de-telefonos-celulares","83":"product_tag-mail-marketing","84":"product_tag-mailing-list","85":"product_tag-marketing","86":"product_tag-marketing-correo-electronico","87":"product_tag-marketing-lists","88":"product_tag-mobile","89":"product_tag-mobile-database","90":"product_tag-mobile-directory","91":"product_tag-mobile-list","92":"product_tag-mobile-number-database","93":"product_tag-mobile-number-list","94":"product_tag-mobile-phone-number","95":"product_tag-numeros-de-telefonos-celulares","96":"product_tag-phone","97":"product_tag-phone-database","98":"product_tag-phone-lists","99":"product_tag-phone-number","100":"product_tag-phone-number-list","101":"product_tag-publicidad-por-base-de-datos-correo-electronico","102":"product_tag-tele-marketing-list","103":"product_tag-telefono","105":"first","106":"instock","107":"sale","108":"virtual","109":"purchasable","110":"product-type-simple","111":"entry","112":"content-bg","113":"loop-entry"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product\/34624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product\/34624\/revisions"}],"predecessor-version":[{"id":34669,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product\/34624\/revisions\/34669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/media\/31021"}],"wp:attachment":[{"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/media?parent=34624"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product_brand?post=34624"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product_cat?post=34624"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product_tag?post=34624"},{"taxonomy":"product_brands","embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product_brands?post=34624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}