{"id":34137,"date":"2025-12-12T16:48:09","date_gmt":"2025-12-12T16:48:09","guid":{"rendered":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/?post_type=product&#038;p=34137"},"modified":"2025-12-12T16:48:28","modified_gmt":"2025-12-12T16:48:28","slug":"inversionistas-ejecutivos-de-alto-nivel-duenos-de-empresas-con-ingresos-mayores-a-70000-00-pesos-mensuales-segmentado-por-colonias-en-ciudad-de-mexico","status":"publish","type":"product","link":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/product\/inversionistas-ejecutivos-de-alto-nivel-duenos-de-empresas-con-ingresos-mayores-a-70000-00-pesos-mensuales-segmentado-por-colonias-en-ciudad-de-mexico\/","title":{"rendered":"Inversionistas, Ejecutivos de alto Nivel, Due\u00f1os de empresas con ingresos mayores a $70,000.00 pesos mensuales, segmentado por colonias en  ciudad de M\u00e9xico."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n<div class=\"row\">\n<div class=\"col-sm\"><strong>C\u00f3digo:<\/strong> <span style=\"color: #ff0000;\"><strong>JWKA-0D<\/strong><\/span><\/div>\n<div class=\"col-sm\"><strong>N\u00famero de registros: 250<\/strong><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm \"><strong>Folio: <span style=\"color: #ff0000;\">KA0417B063<\/span><\/strong><\/div>\n<\/div>\n<p><strong>Segmentaci\u00f3n:<\/strong><\/p>\n<div class=\"row\">\n<div class=\"col-sm \">Inversionistas, Ejecutivos de alto Nivel, Due\u00f1os de empresas con ingresos netos mayores a $70,000.00 pesos mensuales en las colonias: Polanco, Reforma, Roma, La Condesa, Santa Fe, Interlomas, Lomas de Chapultepec en la Ciudad de M\u00e9xico.<\/div>\n<\/div>\n<p><strong>Campos Contenidos:<\/strong><\/p>\n<div class=\"row\">\n<div class=\"col-sm \">Nombre \/ Puesto \/ Empresa \/ Tel\u00e9fono \/ Correo.<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm\"><strong>Garant\u00eda:\u00a0<\/strong>65%-75%\u00a0<strong>Precio Original:\u00a0<\/strong><span style=\"color: #000000;\"><del>$174 USD<\/del><\/span> <strong>Descuento Especial:\u00a0<\/strong><span style=\"color: #ff0000;\"><strong class=\"text-danger\">35%<\/strong><\/span><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col text-center\"><strong>Total a Pagar:\u00a0<\/strong><span style=\"color: #ff0000;\"><strong class=\"text-danger\">$113 USD<\/strong><\/span><\/div>\n<\/div>\n","protected":false},"featured_media":31002,"template":"","meta":{"_bst_post_transparent":"","_bst_post_title":"","_bst_post_layout":"","_bst_post_sidebar_id":"","_bst_post_content_style":"","_bst_post_vertical_padding":"","_bst_post_feature":"","_bst_post_feature_position":"","_bst_post_header":false,"_bst_post_footer":false},"product_brand":[],"product_cat":[1181,1180],"product_tag":[1062,1182,1063,1064,1066,1067,1068,1185,1186,1071,1073,1074,1075,1076,1077,1078,1079,1081,1156,1082,1083,1084,1085,1086,1161,1162,1088,1089,1090,1092,1189,1093,1097,1098,1099,1100,1101,1102,1104,1165,1105,1106,1107,1190,1117,1118,1191,1192,1193,1194,1195,1196,1197,1198,1199,1200,1201,1202,1203,1204,1170,1126,1280,1133,1135,1136,1137,1138,1139,1140,1142,1143,1144,1145,1206,1172,1173,1174,1175,1146,1148,1149],"product_brands":[],"class_list":{"0":"post-34137","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-empresarios","7":"product_cat-personas-en-mexico","8":"product_tag-b2c-email-database","9":"product_tag-base-de-datos","10":"product_tag-base-de-datos-campana-de-email-marketing","11":"product_tag-base-de-datos-campanas-de-email-marketing","12":"product_tag-base-de-datos-ciudad-de-mexico","13":"product_tag-base-de-datos-correo-masivo","14":"product_tag-base-de-datos-correo-masivos","15":"product_tag-base-de-datos-de-empresarios","16":"product_tag-base-de-datos-de-personas-fisicas","17":"product_tag-base-de-datos-direct-e-mail-marketing","18":"product_tag-base-de-datos-e-mail-marketing","19":"product_tag-base-de-datos-email-marketer","20":"product_tag-base-de-datos-email-marketing","21":"product_tag-base-de-datos-email-masivos","22":"product_tag-base-de-datos-email-publicidad","23":"product_tag-base-de-datos-email-publicitario","24":"product_tag-base-de-datos-emailing","25":"product_tag-base-de-datos-enviar-email-masivo","26":"product_tag-base-de-datos-enviar-mailing","27":"product_tag-base-de-datos-envio-de-email-masivo","28":"product_tag-base-de-datos-envio-masivo-correo","29":"product_tag-base-de-datos-envio-masivo-correos","30":"product_tag-base-de-datos-envio-masivo-de-emails","31":"product_tag-base-de-datos-envios-de-correo-masivos","32":"product_tag-base-de-datos-mailing","33":"product_tag-base-de-datos-mailing-masivo","34":"product_tag-base-de-datos-marketing","35":"product_tag-base-de-datos-marketing-por-e-mail","36":"product_tag-base-de-datos-marketing-por-email","37":"product_tag-base-de-datos-para-marketing","38":"product_tag-base-de-datos-personas-de-email-marketing","39":"product_tag-base-de-datos-publicidad-por-email","40":"product_tag-bases-de-datos-correos","41":"product_tag-bases-de-datos-correos-electronicos","42":"product_tag-bases-de-datos-de-emails","43":"product_tag-bases-de-datos-de-marketing","44":"product_tag-bases-de-datos-de-telefonos","45":"product_tag-bases-de-datos-email","46":"product_tag-bases-de-datos-emailing","47":"product_tag-bases-de-datos-mailing","48":"product_tag-bases-de-datos-numeros-de-telefonos","49":"product_tag-bases-de-datos-telefono","50":"product_tag-bases-de-datos-telefonos-fijos","51":"product_tag-big-consumer-database","52":"product_tag-buy-email-list","53":"product_tag-buy-email-list-database","54":"product_tag-consumer-contact-lists","55":"product_tag-consumer-database","56":"product_tag-consumer-directory","57":"product_tag-consumer-email-database","58":"product_tag-consumer-email-list","59":"product_tag-consumer-email-lists","60":"product_tag-consumer-list","61":"product_tag-consumer-mailing-database","62":"product_tag-consumer-mailing-list","63":"product_tag-consumer-mailing-lists","64":"product_tag-consumer-phone-list","65":"product_tag-correo-de-personas","66":"product_tag-correos-electronicos-de-personas","67":"product_tag-correos-electronicos-personas","68":"product_tag-database","69":"product_tag-directorio-emailing","70":"product_tag-duenos","71":"product_tag-email-address-list","72":"product_tag-email-lists","73":"product_tag-email-marketing-list","74":"product_tag-list-of-email-addresses","75":"product_tag-lista-de-correos","76":"product_tag-lista-de-correos-electronicos","77":"product_tag-mail-marketing","78":"product_tag-mailing-list","79":"product_tag-marketing","80":"product_tag-marketing-correo-electronico","81":"product_tag-marketing-lists","82":"product_tag-phone","83":"product_tag-phone-database","84":"product_tag-phone-lists","85":"product_tag-phone-number","86":"product_tag-phone-number-list","87":"product_tag-publicidad-por-base-de-datos-correo-electronico","88":"product_tag-tele-marketing-list","89":"product_tag-telefono","91":"first","92":"instock","93":"sale","94":"shipping-taxable","95":"purchasable","96":"product-type-simple","97":"entry","98":"content-bg","99":"loop-entry"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product\/34137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product\/34137\/revisions"}],"predecessor-version":[{"id":34167,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product\/34137\/revisions\/34167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/media\/31002"}],"wp:attachment":[{"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/media?parent=34137"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product_brand?post=34137"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product_cat?post=34137"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product_tag?post=34137"},{"taxonomy":"product_brands","embeddable":true,"href":"https:\/\/edirectorios.com.mx\/directorios-latinoamerica\/wp-json\/wp\/v2\/product_brands?post=34137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}